{"id":291,"count":3,"description":"","link":"https:\/\/usaontheweb.com\/lingerie\/tag\/chair\/","name":"chair","slug":"chair","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/usaontheweb.com\/lingerie\/wp-json\/wp\/v2\/tags\/291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usaontheweb.com\/lingerie\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/usaontheweb.com\/lingerie\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/usaontheweb.com\/lingerie\/wp-json\/wp\/v2\/posts?tags=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}